{"id":3284,"date":"2018-03-14T13:50:35","date_gmt":"2018-03-14T12:50:35","guid":{"rendered":"http:\/\/www.antegma.com\/?page_id=3284"},"modified":"2024-06-29T17:37:48","modified_gmt":"2024-06-29T15:37:48","slug":"sp","status":"publish","type":"page","link":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/","title":{"rendered":"antegma ACCALLI\/O SP &#8211; Microsoft Sharepoint Integration"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3284\" class=\"elementor elementor-3284\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c97af3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c97af3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2876520\" data-id=\"2876520\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3db176 elementor-widget elementor-widget-image\" data-id=\"b3db176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/antegma_accallio_product_SP-300x300.png\" class=\"attachment-medium size-medium wp-image-3803\" alt=\"\" srcset=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/antegma_accallio_product_SP-300x300.png 300w, https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/antegma_accallio_product_SP-150x150.png 150w, https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/antegma_accallio_product_SP.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-09ff752\" data-id=\"09ff752\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dad692c elementor-widget elementor-widget-heading\" data-id=\"dad692c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACCALLI\/O SP - Microsoft Sharepoint Integration f\u00fcr Ihren Adobe Experience Manager<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a575df elementor-widget elementor-widget-text-editor\" data-id=\"2a575df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Organisieren und verwalten Sie ihren Arbeitsalltag mithilfe von Microsoft Sharepoint. Team-Seiten, Communities und Dateimanagement\u00a0 sind nur einige der vielen Features die Microsoft Sharepoint beinhaltet. Kombinieren Sie deshalb Ihren Adobe Experience Manager mit Microsoft Sharepoint und profitieren Sie vom Zusammenspiel beider L\u00f6sungen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c846ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c846ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fcb122f\" data-id=\"fcb122f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b707f5 elementor-widget elementor-widget-video\" data-id=\"5b707f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=ovrEEobxLsE&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddce3c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddce3c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65ecdae\" data-id=\"65ecdae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd9b420 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bd9b420\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-541727c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"541727c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf9da3a\" data-id=\"cf9da3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfbb142 elementor-widget elementor-widget-text-editor\" data-id=\"cfbb142\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Microsoft Sharepoint Integration von antegma bietet Ihnen alle n\u00fctzlichen Sharepoint-Funktionen innerhalb Ihrer gewohnten Adobe Experience Manager Umgebung. Steigern Sie Ihre Effizienz, indem Sie mithilfe von Microsoft Sharepoint Ihren Arbeitsalltag verwalten. Individuelle Team-Seiten und Communities, sowie das Dateimanagement und Filesharing sind im Funktionsumfang enthalten. Das Verwalten, Speichern und Versionieren Ihrer Dokumente ist in den \u00fcblichen Microsoft Office Dateiformaten m\u00f6glich und erleichtert auch die Bearbeitung der Dateien im Web. Das komplette User Interface kann nach Ihren W\u00fcnschen angepasst und erweitert werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bc2b95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bc2b95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55d781c\" data-id=\"55d781c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bcea2c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4bcea2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay&quot;:&quot;no&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4bcea2c\" data-elementor-lightbox-title=\"20190124_SP_Marketplace_final\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc1MywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbnRlZ21hLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMDFcLzIwMTkwMTI0X1NQX01hcmtldHBsYWNlX2ZpbmFsLmpwZyIsInNsaWRlc2hvdyI6IjRiY2VhMmMifQ%3D%3D\" href=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/20190124_SP_Marketplace_final.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/20190124_SP_Marketplace_final-300x169.jpg\" alt=\"20190124_SP_Marketplace_final\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4bcea2c\" data-elementor-lightbox-title=\"screenshot_1_1280x720\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDMzNSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbnRlZ21hLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMDlcL3NjcmVlbnNob3RfMV8xMjgweDcyMC5qcGciLCJzbGlkZXNob3ciOiI0YmNlYTJjIn0%3D\" href=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_1_1280x720.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_1_1280x720-300x169.jpg\" alt=\"screenshot_1_1280x720\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4bcea2c\" data-elementor-lightbox-title=\"screenshot_3_1280x720\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDMzOSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbnRlZ21hLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMDlcL3NjcmVlbnNob3RfM18xMjgweDcyMC5qcGciLCJzbGlkZXNob3ciOiI0YmNlYTJjIn0%3D\" href=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_3_1280x720.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_3_1280x720-300x169.jpg\" alt=\"screenshot_3_1280x720\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4bcea2c\" data-elementor-lightbox-title=\"screenshot_4_1280x720\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDMyNywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbnRlZ21hLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMDlcL3NjcmVlbnNob3RfNF8xMjgweDcyMC5qcGciLCJzbGlkZXNob3ciOiI0YmNlYTJjIn0%3D\" href=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_4_1280x720.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_4_1280x720-300x169.jpg\" alt=\"screenshot_4_1280x720\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4bcea2c\" data-elementor-lightbox-title=\"screenshot_6_1280x720\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDMzMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hbnRlZ21hLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMDlcL3NjcmVlbnNob3RfNl8xMjgweDcyMC5qcGciLCJzbGlkZXNob3ciOiI0YmNlYTJjIn0%3D\" href=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_6_1280x720.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_6_1280x720-300x169.jpg\" alt=\"screenshot_6_1280x720\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4bcea2c\" data-elementor-lightbox-title=\"screenshot_7_1280x720\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDMzMywidXJsIjoiaHR0cHM6XC9cL3d3dy5hbnRlZ21hLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMDlcL3NjcmVlbnNob3RfN18xMjgweDcyMC5qcGciLCJzbGlkZXNob3ciOiI0YmNlYTJjIn0%3D\" href=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_7_1280x720.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/09\/screenshot_7_1280x720-300x169.jpg\" alt=\"screenshot_7_1280x720\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dbc54e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dbc54e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1b152c7\" data-id=\"1b152c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95735ae elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"95735ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-import\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M16 288c-8.8 0-16 7.2-16 16v32c0 8.8 7.2 16 16 16h112v-64zm489-183L407.1 7c-4.5-4.5-10.6-7-17-7H384v128h128v-6.1c0-6.3-2.5-12.4-7-16.9zm-153 31V0H152c-13.3 0-24 10.7-24 24v264h128v-65.2c0-14.3 17.3-21.4 27.4-11.3L379 308c6.6 6.7 6.6 17.4 0 24l-95.7 96.4c-10.1 10.1-27.4 3-27.4-11.3V352H128v136c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H376c-13.2 0-24-10.8-24-24z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDateimanagement\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tErstellen, Versionieren und Teilen Sie Ihre Dateien. Mithilfe von Microsoft Sharepoint stellen Sie sicher, dass wichtige Informationen stets abrufbar sind.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a0fbd18\" data-id=\"a0fbd18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81014e6 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"81014e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-code\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M278.9 511.5l-61-17.7c-6.4-1.8-10-8.5-8.2-14.9L346.2 8.7c1.8-6.4 8.5-10 14.9-8.2l61 17.7c6.4 1.8 10 8.5 8.2 14.9L293.8 503.3c-1.9 6.4-8.5 10.1-14.9 8.2zm-114-112.2l43.5-46.4c4.6-4.9 4.3-12.7-.8-17.2L117 256l90.6-79.7c5.1-4.5 5.5-12.3.8-17.2l-43.5-46.4c-4.5-4.8-12.1-5.1-17-.5L3.8 247.2c-5.1 4.7-5.1 12.8 0 17.5l144.1 135.1c4.9 4.6 12.5 4.4 17-.5zm327.2.6l144.1-135.1c5.1-4.7 5.1-12.8 0-17.5L492.1 112.1c-4.8-4.5-12.4-4.3-17 .5L431.6 159c-4.6 4.9-4.3 12.7.8 17.2L523 256l-90.6 79.7c-5.1 4.5-5.5 12.3-.8 17.2l43.5 46.4c4.5 4.9 12.1 5.1 17 .6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIntegration\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNutzen Sie Microsoft Sharepoint innerhalb Ihrer Adobe Experience Manager L\u00f6sung und kombinieren Sie zwei separate Plattformen in einem System.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-297fcb5\" data-id=\"297fcb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7d5a2b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b7d5a2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFormat\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNutzen Sie Microsoft Dateiformate die sie von Ihren Desktop-Anwendungen kennen auch im Web. Bearbeiten Sie Dateien wie gewohnt.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa2c314 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa2c314\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-006f774\" data-id=\"006f774\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb4a12a elementor-widget elementor-widget-heading\" data-id=\"fb4a12a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Folgende Sharepoint-Features werden derzeit unterst\u00fctzt<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4877396 elementor-widget elementor-widget-text-editor\" data-id=\"4877396\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Files &amp; Ordner<\/li><li>Eigene Seiten<\/li><li>Benutzer und Gruppen<\/li><li>Social (Feeds, Profiles, Following)<\/li><li>Such-Funktion<\/li><li>Single Sign-On im Adobe Experience Manager f\u00fcr den Microsoft Sharepoint-Zugriff<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-414cdb24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"414cdb24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-103bf56f\" data-id=\"103bf56f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f0e4c23 elementor-widget elementor-widget-heading\" data-id=\"5f0e4c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Synergien<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6788907c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6788907c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7a6b1286\" data-id=\"7a6b1286\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-138c53ff elementor-widget elementor-widget-image\" data-id=\"138c53ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2018\/02\/antegma_accallio_product_example1-300x300.png\" class=\"attachment-medium size-medium wp-image-3167\" alt=\"\" srcset=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2018\/02\/antegma_accallio_product_example1-300x300.png 300w, https:\/\/www.antegma.com\/wp-content\/uploads\/2018\/02\/antegma_accallio_product_example1-150x150.png 150w, https:\/\/www.antegma.com\/wp-content\/uploads\/2018\/02\/antegma_accallio_product_example1-768x768.png 768w, https:\/\/www.antegma.com\/wp-content\/uploads\/2018\/02\/antegma_accallio_product_example1.png 827w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-303a7d93\" data-id=\"303a7d93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c97e893 elementor-widget elementor-widget-text-editor\" data-id=\"4c97e893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Profitieren Sie von einem ma\u00dfgeschneiderten Softwarepaket, das perfekt zu den Anforderungen Ihres Unternehmens passt. ACCALLI\/O ist eine ma\u00dfgeschneiderte L\u00f6sung, die getrennte Anwendungen in eine Plattform integriert, um Synergien zu nutzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bb8579f elementor-widget elementor-widget-button\" data-id=\"7bb8579f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.antegma.com\/de\/products\/accallio\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hier weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22666f0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22666f0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-754f5b4f\" data-id=\"754f5b4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14c0910 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"14c0910\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4092bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4092bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37ab3d4c\" data-id=\"37ab3d4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28cd888 elementor-widget elementor-widget-image\" data-id=\"28cd888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/antegma_accallio_product_example2_OX-300x300.png\" class=\"attachment-medium size-medium wp-image-3801\" alt=\"\" srcset=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/antegma_accallio_product_example2_OX-300x300.png 300w, https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/antegma_accallio_product_example2_OX-150x150.png 150w, https:\/\/www.antegma.com\/wp-content\/uploads\/2019\/01\/antegma_accallio_product_example2_OX.png 679w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6feb52a3\" data-id=\"6feb52a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51ae771e elementor-widget elementor-widget-heading\" data-id=\"51ae771e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ACCALLI\/O\u00a0OX - Microsoft Office 365 Outlook &amp; Exchange Integration f\u00fcr den Adobe Experience Manager<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4520885c elementor-widget elementor-widget-text-editor\" data-id=\"4520885c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Bringen Sie die erfolgreichste Business Software in einen neuen Kontext mit unserer Integration. Schaffen Sie optimierte Prozesse und ein nahtloses Benutzererlebnis indem Sie Microsoft\u00a0Office 365 Outlook &amp; Exchange Integration in den Adobe Experience Manager bringen. Verfassen Sie Mails, Bearbeiten Sie Kontakte und Termine. Alle Features sind als Komponenten in AEM verf\u00fcgbar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-296195e6 elementor-widget elementor-widget-button\" data-id=\"296195e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.antegma.com\/de\/products\/accallio\/ox\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hier weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-477aaa2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"477aaa2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fd0e65a\" data-id=\"2fd0e65a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66cfd52c elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"66cfd52c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ced6c64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ced6c64\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4ca54fb\" data-id=\"4ca54fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c315668 elementor-widget elementor-widget-image\" data-id=\"c315668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2020\/05\/antegma_accallio_product_dy-300x300.png\" class=\"attachment-medium size-medium wp-image-4823\" alt=\"\" srcset=\"https:\/\/www.antegma.com\/wp-content\/uploads\/2020\/05\/antegma_accallio_product_dy-300x300.png 300w, https:\/\/www.antegma.com\/wp-content\/uploads\/2020\/05\/antegma_accallio_product_dy-150x150.png 150w, https:\/\/www.antegma.com\/wp-content\/uploads\/2020\/05\/antegma_accallio_product_dy.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9a0e402\" data-id=\"9a0e402\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ad3820 elementor-widget elementor-widget-heading\" data-id=\"5ad3820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ACCALLI\/O&nbsp;DY - Microsoft Dynamics 365 Integration f\u00fcr den Adobe Experience Manager<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24ffa1c elementor-widget elementor-widget-text-editor\" data-id=\"24ffa1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75e9e88 elementor-widget elementor-widget-text-editor\" data-id=\"75e9e88\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>Realisieren integrierte Kundenerlebnisse und verbinden Sie die Funktionen von Microsoft Dynamics 365 mit dem Adobe Experience Manager.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dabdd74 elementor-widget elementor-widget-button\" data-id=\"dabdd74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.antegma.com\/de\/products\/accallio\/dy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hier weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-532b5699 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"532b5699\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e761255\" data-id=\"7e761255\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34c53319 elementor-widget elementor-widget-text-editor\" data-id=\"34c53319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Haben wir Ihr\u00a0<strong>Interesse<\/strong> geweckt?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7247a5f4 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7247a5f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.antegma.com\/de\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktieren Sie uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-249a361f\" data-id=\"249a361f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Entdecken Sie antegma ACCALLI\/O SP, die nahtlose Integration von Microsoft SharePoint und OneDrive f\u00fcr Adobe Experience Manager Sites. Optimieren Sie Ihre Arbeitsabl\u00e4ufe mit dieser leistungsstarken L\u00f6sung f\u00fcr die Verwaltung und Zusammenarbeit mit Inhalten in AEM. Erfahren Sie mehr \u00fcber ACCALLI\/O SP und wie es Ihnen hilft, Effizienz und Produktivit\u00e4t zu steigern.<\/p>\n","protected":false},"author":5,"featured_media":6903,"parent":2982,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3284","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>antegma ACCALLI\/O SP - Microsoft Sharepoint Integration | antegma<\/title>\n<meta name=\"description\" content=\"Entdecken Sie antegma ACCALLI\/O SP, die nahtlose Integration von Microsoft SharePoint und OneDrive f\u00fcr Adobe Experience Manager Sites. Optimieren Sie Ihre Arbeitsabl\u00e4ufe mit dieser leistungsstarken L\u00f6sung f\u00fcr die Verwaltung und Zusammenarbeit mit Inhalten in AEM. Erfahren Sie mehr \u00fcber ACCALLI\/O SP und wie es Ihnen hilft, Effizienz und Produktivit\u00e4t zu steigern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"antegma ACCALLI\/O SP - Microsoft Sharepoint Integration\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie antegma ACCALLI\/O SP, die nahtlose Integration von Microsoft SharePoint und OneDrive f\u00fcr Adobe Experience Manager Sites. Optimieren Sie Ihre Arbeitsabl\u00e4ufe mit dieser leistungsstarken L\u00f6sung f\u00fcr die Verwaltung und Zusammenarbeit mit Inhalten in AEM. Erfahren Sie mehr \u00fcber ACCALLI\/O SP und wie es Ihnen hilft, Effizienz und Produktivit\u00e4t zu steigern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/\" \/>\n<meta property=\"og:site_name\" content=\"antegma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antegma\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-29T15:37:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/antegmawebsite.blob.core.windows.net\/website\/wp-content\/uploads\/2021\/04\/AdobeStock_323998540-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@antegma\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/sp\\\/\",\"url\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/sp\\\/\",\"name\":\"antegma ACCALLI\\\/O SP - Microsoft Sharepoint Integration | antegma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/sp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/sp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.antegma.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/AdobeStock_323998540-scaled.jpeg\",\"datePublished\":\"2018-03-14T12:50:35+00:00\",\"dateModified\":\"2024-06-29T15:37:48+00:00\",\"description\":\"Entdecken Sie antegma ACCALLI\\\/O SP, die nahtlose Integration von Microsoft SharePoint und OneDrive f\u00fcr Adobe Experience Manager Sites. Optimieren Sie Ihre Arbeitsabl\u00e4ufe mit dieser leistungsstarken L\u00f6sung f\u00fcr die Verwaltung und Zusammenarbeit mit Inhalten in AEM. Erfahren Sie mehr \u00fcber ACCALLI\\\/O SP und wie es Ihnen hilft, Effizienz und Produktivit\u00e4t zu steigern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/sp\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/sp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/sp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.antegma.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/AdobeStock_323998540-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.antegma.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/AdobeStock_323998540-scaled.jpeg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"antegma ACCALLI\\\/O\",\"item\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/products\\\/accallio\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"antegma ACCALLI\\\/O SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/\",\"name\":\"antegma\",\"description\":\"Ihr Partner f\u00fcr die Digitale Transformation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/#organization\",\"name\":\"antegma GmbH\",\"alternateName\":\"antegma\",\"url\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.antegma.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/antegma-logo-white-quadratisch.png\",\"contentUrl\":\"https:\\\/\\\/www.antegma.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/antegma-logo-white-quadratisch.png\",\"width\":300,\"height\":300,\"caption\":\"antegma GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.antegma.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/antegma\",\"https:\\\/\\\/x.com\\\/antegma\",\"https:\\\/\\\/www.instagram.com\\\/antegma\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/antegma-gmbh\",\"https:\\\/\\\/www.youtube.com\\\/@antegma\",\"https:\\\/\\\/solutionpartners.adobe.com\\\/s\\\/directory\\\/detail\\\/antegma\",\"https:\\\/\\\/exchange.adobe.com\\\/publisher\\\/ec\\\/2a398941-2c20-49ef-bf6e-b35e902cad15\\\/antegma-gmbh\"],\"description\":\"antegma is specializing in digital transformation consulting and implementation. Based in Germany with offices in Munich and St. Georgen, we help enterprises optimize their content supply chain, work management, digital marketing, digital experience, e-commerce, data & AI, and system integrations. We are partners of Adobe, Canto, Hootsuite, Microsoft, Monday.com.\",\"email\":\"info@antegma.com\",\"telephone\":\"+49 89 55270890\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"antegma ACCALLI\/O SP - Microsoft Sharepoint Integration | antegma","description":"Entdecken Sie antegma ACCALLI\/O SP, die nahtlose Integration von Microsoft SharePoint und OneDrive f\u00fcr Adobe Experience Manager Sites. Optimieren Sie Ihre Arbeitsabl\u00e4ufe mit dieser leistungsstarken L\u00f6sung f\u00fcr die Verwaltung und Zusammenarbeit mit Inhalten in AEM. Erfahren Sie mehr \u00fcber ACCALLI\/O SP und wie es Ihnen hilft, Effizienz und Produktivit\u00e4t zu steigern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/","og_locale":"de_DE","og_type":"article","og_title":"antegma ACCALLI\/O SP - Microsoft Sharepoint Integration","og_description":"Entdecken Sie antegma ACCALLI\/O SP, die nahtlose Integration von Microsoft SharePoint und OneDrive f\u00fcr Adobe Experience Manager Sites. Optimieren Sie Ihre Arbeitsabl\u00e4ufe mit dieser leistungsstarken L\u00f6sung f\u00fcr die Verwaltung und Zusammenarbeit mit Inhalten in AEM. Erfahren Sie mehr \u00fcber ACCALLI\/O SP und wie es Ihnen hilft, Effizienz und Produktivit\u00e4t zu steigern.","og_url":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/","og_site_name":"antegma","article_publisher":"https:\/\/www.facebook.com\/antegma","article_modified_time":"2024-06-29T15:37:48+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/antegmawebsite.blob.core.windows.net\/website\/wp-content\/uploads\/2021\/04\/AdobeStock_323998540-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@antegma","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/","url":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/","name":"antegma ACCALLI\/O SP - Microsoft Sharepoint Integration | antegma","isPartOf":{"@id":"https:\/\/www.antegma.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/#primaryimage"},"image":{"@id":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.antegma.com\/wp-content\/uploads\/2021\/04\/AdobeStock_323998540-scaled.jpeg","datePublished":"2018-03-14T12:50:35+00:00","dateModified":"2024-06-29T15:37:48+00:00","description":"Entdecken Sie antegma ACCALLI\/O SP, die nahtlose Integration von Microsoft SharePoint und OneDrive f\u00fcr Adobe Experience Manager Sites. Optimieren Sie Ihre Arbeitsabl\u00e4ufe mit dieser leistungsstarken L\u00f6sung f\u00fcr die Verwaltung und Zusammenarbeit mit Inhalten in AEM. Erfahren Sie mehr \u00fcber ACCALLI\/O SP und wie es Ihnen hilft, Effizienz und Produktivit\u00e4t zu steigern.","breadcrumb":{"@id":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/#primaryimage","url":"https:\/\/www.antegma.com\/wp-content\/uploads\/2021\/04\/AdobeStock_323998540-scaled.jpeg","contentUrl":"https:\/\/www.antegma.com\/wp-content\/uploads\/2021\/04\/AdobeStock_323998540-scaled.jpeg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.antegma.com\/de\/products\/accallio\/sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.antegma.com\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/www.antegma.com\/de\/products\/"},{"@type":"ListItem","position":3,"name":"antegma ACCALLI\/O","item":"https:\/\/www.antegma.com\/de\/products\/accallio\/"},{"@type":"ListItem","position":4,"name":"antegma ACCALLI\/O SP"}]},{"@type":"WebSite","@id":"https:\/\/www.antegma.com\/de\/#website","url":"https:\/\/www.antegma.com\/de\/","name":"antegma","description":"Ihr Partner f\u00fcr die Digitale Transformation","publisher":{"@id":"https:\/\/www.antegma.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.antegma.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.antegma.com\/de\/#organization","name":"antegma GmbH","alternateName":"antegma","url":"https:\/\/www.antegma.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.antegma.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.antegma.com\/wp-content\/uploads\/2024\/11\/antegma-logo-white-quadratisch.png","contentUrl":"https:\/\/www.antegma.com\/wp-content\/uploads\/2024\/11\/antegma-logo-white-quadratisch.png","width":300,"height":300,"caption":"antegma GmbH"},"image":{"@id":"https:\/\/www.antegma.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/antegma","https:\/\/x.com\/antegma","https:\/\/www.instagram.com\/antegma","https:\/\/www.linkedin.com\/company\/antegma-gmbh","https:\/\/www.youtube.com\/@antegma","https:\/\/solutionpartners.adobe.com\/s\/directory\/detail\/antegma","https:\/\/exchange.adobe.com\/publisher\/ec\/2a398941-2c20-49ef-bf6e-b35e902cad15\/antegma-gmbh"],"description":"antegma is specializing in digital transformation consulting and implementation. Based in Germany with offices in Munich and St. Georgen, we help enterprises optimize their content supply chain, work management, digital marketing, digital experience, e-commerce, data & AI, and system integrations. We are partners of Adobe, Canto, Hootsuite, Microsoft, Monday.com.","email":"info@antegma.com","telephone":"+49 89 55270890","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"_links":{"self":[{"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/pages\/3284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/comments?post=3284"}],"version-history":[{"count":0,"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/pages\/3284\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/pages\/2982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/media\/6903"}],"wp:attachment":[{"href":"https:\/\/www.antegma.com\/de\/wp-json\/wp\/v2\/media?parent=3284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}